{"id":554,"count":3,"description":"Il casin\u00f2 si impegna anche a proteggere i minori, verificando l'et\u00e0 degli utenti durante la iscrizione e monitorando attivamente l'attivit\u00e0 dei giocatori. -","link":"https:\/\/www.mannindia.com\/medicalandsafety\/category\/betonred-casino-704\/","name":"Betonred Casino 704","slug":"betonred-casino-704","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.mannindia.com\/medicalandsafety\/wp-json\/wp\/v2\/categories\/554"}],"collection":[{"href":"https:\/\/www.mannindia.com\/medicalandsafety\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.mannindia.com\/medicalandsafety\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.mannindia.com\/medicalandsafety\/wp-json\/wp\/v2\/posts?categories=554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}